{"id":885,"date":"2025-07-08T03:10:55","date_gmt":"2025-07-08T03:10:55","guid":{"rendered":"https:\/\/www.nakok.go.th\/th\/?p=885"},"modified":"2026-03-20T03:19:05","modified_gmt":"2026-03-20T03:19:05","slug":"%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2-3","status":"publish","type":"post","link":"https:\/\/www.nakok.go.th\/th\/%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2-3\/","title":{"rendered":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e33\u0e1a\u0e25\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e04\u0e01 \u0e2a\u0e21\u0e31\u0e22\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 1 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2568"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>0 Second                <\/div>\n\n            <\/div>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"886\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_2-1024x768.jpg\" alt=\"\" class=\"wp-image-886\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_2-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_2-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_2-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_2.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"892\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_3-1024x768.jpg\" alt=\"\" class=\"wp-image-892\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_3-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_3-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_3-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_3.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"890\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_4-1024x768.jpg\" alt=\"\" class=\"wp-image-890\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_4-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_4-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_4-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_4.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"887\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_5-1024x768.jpg\" alt=\"\" class=\"wp-image-887\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_5-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_5-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_5-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_5.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"891\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_7-1024x768.jpg\" alt=\"\" class=\"wp-image-891\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_7-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_7-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_7-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_7.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"896\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_8-1024x768.jpg\" alt=\"\" class=\"wp-image-896\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_8-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_8-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_8-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_8.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"898\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_9-1024x768.jpg\" alt=\"\" class=\"wp-image-898\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_9-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_9-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_9-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_9.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"899\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_10-1024x768.jpg\" alt=\"\" class=\"wp-image-899\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_10-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_10-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_10-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_10.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"897\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_11-1024x768.jpg\" alt=\"\" class=\"wp-image-897\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_11-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_11-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_11-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_11.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"888\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_12-1024x768.jpg\" alt=\"\" class=\"wp-image-888\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_12-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_12-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_12-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_12.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"893\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_13-1024x768.jpg\" alt=\"\" class=\"wp-image-893\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_13-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_13-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_13-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_13.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"895\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_14-1024x768.jpg\" alt=\"\" class=\"wp-image-895\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_14-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_14-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_14-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_14.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"894\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_15-1024x768.jpg\" alt=\"\" class=\"wp-image-894\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_15-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_15-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_15-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_15.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"900\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_16-1024x768.jpg\" alt=\"\" class=\"wp-image-900\" srcset=\"https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_16-1024x768.jpg 1024w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_16-300x225.jpg 300w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_16-768x576.jpg 768w, https:\/\/www.nakok.go.th\/th\/wp-content\/uploads\/2026\/03\/LINE_ALBUM_\u0e27\u0e34\u0e2a\u0e32\u0e21\u0e31\u0e22-\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48-1_250815_16.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n        <div class=\"booster-block booster-reactions-block\">\n            <div class=\"twp-reactions-icons\">\n                \n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-1\" post-id=\"885\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/happy.svg\" alt=\"Happy\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Happy                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                        \n                                                <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-2\" post-id=\"885\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/sad.svg\" alt=\"Sad\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Sad                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                                                                        <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-3\" post-id=\"885\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/excited.svg\" alt=\"Excited\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Excited                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                                                                        <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-6\" post-id=\"885\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/sleepy.svg\" alt=\"Sleepy\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Sleepy                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                        \n                                                <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-4\" post-id=\"885\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/angry.svg\" alt=\"Angry\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">Angry<\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                                                                        <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                        \n                    <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-5\" post-id=\"885\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.nakok.go.th\/th\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/surprise.svg\" alt=\"Surprise\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">Surprise<\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                                                                        <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n            <\/div>\n        <\/div>\n\n    ","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-19"],"_links":{"self":[{"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/posts\/885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/comments?post=885"}],"version-history":[{"count":2,"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/posts\/885\/revisions"}],"predecessor-version":[{"id":937,"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/posts\/885\/revisions\/937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/media\/936"}],"wp:attachment":[{"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/media?parent=885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/categories?post=885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nakok.go.th\/th\/wp-json\/wp\/v2\/tags?post=885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}